
{"id":52,"count":8,"description":"","link":"https:\/\/www.mbscottsdale.com\/blog\/category\/slc\/","name":"Mercedes-Benz SLC","slug":"slc","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<link rel=\"canonical\" href=\"https:\/\/www.mbscottsdale.com\/blog\/category\/slc\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercedes-Benz SLC Archives - Mercedes-Benz of Scottsdale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mbscottsdale.com\/blog\/category\/slc\/\" \/>\n<meta property=\"og:site_name\" content=\"Mercedes-Benz of Scottsdale\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mbscottsdale.com\/blog\/#website\",\"url\":\"https:\/\/www.mbscottsdale.com\/blog\/\",\"name\":\"Mercedes-Benz of Scottsdale\",\"description\":\"Official Blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.mbscottsdale.com\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.mbscottsdale.com\/blog\/category\/slc\/#webpage\",\"url\":\"https:\/\/www.mbscottsdale.com\/blog\/category\/slc\/\",\"name\":\"Mercedes-Benz SLC Archives - Mercedes-Benz of Scottsdale\",\"isPartOf\":{\"@id\":\"https:\/\/www.mbscottsdale.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.mbscottsdale.com\/blog\/category\/slc\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mbscottsdale.com\/blog\/category\/slc\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mbscottsdale.com\/blog\/category\/slc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mbscottsdale.com\/blog\/\",\"url\":\"https:\/\/www.mbscottsdale.com\/blog\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mbscottsdale.com\/blog\/category\/slc\/\",\"url\":\"https:\/\/www.mbscottsdale.com\/blog\/category\/slc\/\",\"name\":\"Mercedes-Benz SLC\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.mbscottsdale.com\/blog\/wp-json\/wp\/v2\/categories\/52"}],"collection":[{"href":"https:\/\/www.mbscottsdale.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.mbscottsdale.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.mbscottsdale.com\/blog\/wp-json\/wp\/v2\/posts?categories=52"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}